{"id":190,"date":"2024-07-21T11:50:52","date_gmt":"2024-07-21T11:50:52","guid":{"rendered":"https:\/\/dockerpros.com\/?p=190"},"modified":"2024-07-21T11:50:52","modified_gmt":"2024-07-21T11:50:52","slug":"so-verknupfen-sie-docker-containerdie-veraltete-methode-mit-link-wird-nicht-mehr-empfohlen-verwenden-sie-stattdessen-benutzerdefinierte-docker-netzwerke1-netzwerk-erstellen-bash","status":"publish","type":"post","link":"https:\/\/dockerpros.com\/de\/container-creation-and-management\/how-do-i-link-docker-containers\/","title":{"rendered":"Wie verkn\u00fcpfe ich Docker-Container?"},"content":{"rendered":"<h1>How to Link Docker Containers: An Advanced Guide<\/h1>\n<p>Docker has revolutionized the way developers build, ship, and <span class=\"glossaryai-tooltip glossary-term-672\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/run\/\" target=\"_blank\">laufen<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">\"RUN\" bezeichnet einen Befehl in verschiedenen Programmiersprachen und Betriebssystemen, um ein angegebenes Programm oder Skript auszuf\u00fchren. Er initiiert Prozesse und stellt eine kontrollierte Ausf\u00fchrungsumgebung f\u00fcr die Aufgabenbereitstellung bereit.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/run\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> Anwendungen durch die Containerisierung - die Kapselung von Software in einer standardisierten Einheit f\u00fcr die Bereitstellung. Einer der wesentlichen Aspekte bei der effektiven Nutzung von Docker ist die F\u00e4higkeit, Container miteinander zu verkn\u00fcpfen, sodass sie nahtlos kommunizieren und Ressourcen teilen k\u00f6nnen. Dieser Artikel wird sich mit fortgeschrittenen Techniken und Konzepten im Zusammenhang mit <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> linking, covering the best practices, potential pitfalls, and alternative methods to achieve <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> intercommunication.<\/p>\n<h2>Understanding Docker Container Linking<\/h2>\n<p><span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Container<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> linking is the process of establishing a connection between two or more Docker containers so they can communicate with each other. When containers are linked, they can easily share information, such as environment variables, <span class=\"glossaryai-tooltip glossary-term-677\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/port\/\" target=\"_blank\">port<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Ein PORT ist ein Kommunikationsendpunkt in einem Computernetzwerk, der durch eine numerische Kennung definiert ist. Er erm\u00f6glicht die Weiterleitung von Daten an bestimmte Anwendungen und verbessert so die Funktionalit\u00e4t und Sicherheit des Systems.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/port\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> mappings, and more. <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Container<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> linking was one of the original methods Docker provided to facilitate communication between containers.<\/p>\n<h3>Grundlagen der Container-Verkn\u00fcpfung<\/h3>\n<p>When you link containers, Docker creates a secure communication channel between them. This is done via environment variables and private IP addresses assigned to each <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span>. When you start a <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> with the <code>--link<\/code> flag, you essentially inform Docker that you wish to connect the specified <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> (the &quot;linked&quot; <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span>) to the current one (the &quot;linking&quot; <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span>).<\/p>\n<h3>Syntax and Example<\/h3>\n<p>Here is the syntax for linking two containers:<\/p>\n<pre><code class=\"language-bash\">docker <span class=\"glossaryai-tooltip glossary-term-672\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/run\/\" target=\"_blank\">laufen<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">\"RUN\" bezeichnet einen Befehl in verschiedenen Programmiersprachen und Betriebssystemen, um ein angegebenes Programm oder Skript auszuf\u00fchren. Er initiiert Prozesse und stellt eine kontrollierte Ausf\u00fchrungsumgebung f\u00fcr die Aufgabenbereitstellung bereit.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/run\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> -d --name my_db mysql\ndocker <span class=\"glossaryai-tooltip glossary-term-672\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/run\/\" target=\"_blank\">laufen<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">\"RUN\" bezeichnet einen Befehl in verschiedenen Programmiersprachen und Betriebssystemen, um ein angegebenes Programm oder Skript auszuf\u00fchren. Er initiiert Prozesse und stellt eine kontrollierte Ausf\u00fchrungsumgebung f\u00fcr die Aufgabenbereitstellung bereit.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/run\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> -d --name my_app --link my_db:mysql my_app_image<\/code><\/pre>\n<p>In this example, we start a MySQL <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> named <code>my_db<\/code> and then <span class=\"glossaryai-tooltip glossary-term-672\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/run\/\" target=\"_blank\">laufen<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">\"RUN\" bezeichnet einen Befehl in verschiedenen Programmiersprachen und Betriebssystemen, um ein angegebenes Programm oder Skript auszuf\u00fchren. Er initiiert Prozesse und stellt eine kontrollierte Ausf\u00fchrungsumgebung f\u00fcr die Aufgabenbereitstellung bereit.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/run\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> an application <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> named <code>my_app<\/code>, linking it to <code>my_db<\/code>. Die <code>--link<\/code> flag automatically adds environment variables such as <code>MYSQL_PORT_3306_TCP<\/code> and <code>MYSQL_ENV_MYSQL_ROOT_PASSWORD<\/code> zu dem <code>my_app<\/code> <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span>.<\/p>\n<h2>Einschr\u00e4nkungen beim Verkn\u00fcpfen von Containern<\/h2>\n<p>While linking containers was a useful feature, it has some limitations and drawbacks that developers should consider:<\/p>\n<h3>1. <strong>Veraltet zugunsten benutzerdefinierter Netzwerke<\/strong><\/h3>\n<p>Docker <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> linking has been deprecated in favor of user-defined networks. With user-defined networks, containers can communicate using their names as hostnames, which is more intuitive and flexible.<\/p>\n<h3>2. <strong>Statische Konfiguration<\/strong><\/h3>\n<p>Links are statically defined at the time of <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> creation. If a <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> needs to be reconfigured or changed, you must recreate the linked containers, which can be cumbersome.<\/p>\n<h3>3. <strong>Sicherheitsbedenken<\/strong><\/h3>\n<p>Links <span class=\"glossaryai-tooltip glossary-term-676\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/expose\/\" target=\"_blank\">exponieren<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">\"EXPOSE\" ist ein leistungsstarkes Werkzeug, das in verschiedenen Bereichen, einschlie\u00dflich Cybersicherheit und Softwareentwicklung, eingesetzt wird, um Schwachstellen und M\u00e4ngel in Systemen zu identifizieren und sicherzustellen, dass robuste Sicherheitsma\u00dfnahmen implementiert werden.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/expose\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> certain environment variables containing sensitive information, such as database passwords. This can lead to unintended access and security vulnerabilities.<\/p>\n<h3>4. <strong>Single Host Limitation<\/strong><\/h3>\n<p><span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Container<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> linking works well on a single host but does not scale effectively in multi-host configurations. For such scenarios, <span class=\"glossaryai-tooltip glossary-term-657\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/orchestration\/\" target=\"_blank\">Orchestrierung<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Orchestrierung bezieht sich auf die automatisierte Verwaltung und Koordination komplexer Systeme und Dienstleistungen. Sie optimiert Prozesse durch die Integration verschiedener Komponenten und gew\u00e4hrleistet so einen effizienten Betrieb und eine optimale Ressourcennutzung.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/orchestration\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> Werkzeuge wie <span class=\"glossaryai-tooltip glossary-term-655\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/docker-swarm\/\" target=\"_blank\">Docker Swarm<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Docker Swarm is a container orchestration tool that enables the management of a cluster of Docker engines. It simplifies scaling and deployment, ensuring high availability and load balancing across services.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/docker-swarm\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> or <span class=\"glossaryai-tooltip glossary-term-656\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/kubernetes\/\" target=\"_blank\">Kubernetes<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Kubernetes ist eine Open-Source-Plattform zur Container-Orchestrierung, die die Bereitstellung, Skalierung und Verwaltung von containerisierten Anwendungen automatisiert und so die Ressourceneffizienz und Resilienz verbessert.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/kubernetes\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> sind angemessener.<\/p>\n<h2>Benutzerdefinierte Netzwerke: Der moderne Ansatz<\/h2>\n<p>In den letzten Jahren hat Docker benutzerdefinierte Netzwerke eingef\u00fchrt, die nun die empfohlene Methode sind, um die Kommunikation zwischen Containern zu erm\u00f6glichen. Dieser Ansatz bietet mehrere Vorteile gegen\u00fcber traditionellen Verkn\u00fcpfungsmethoden.<\/p>\n<h3>Benefits of User-Defined Networks<\/h3>\n<ol>\n<li>\n<p><strong>Flexiblere Kommunikation<\/strong>Container im selben benutzerdefinierten Netzwerk <span class=\"glossaryai-tooltip glossary-term-661\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\" target=\"_blank\">network<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Ein Netzwerk im Bereich der Informatik bezeichnet eine Sammlung miteinander verbundener Ger\u00e4te, die miteinander kommunizieren und Ressourcen teilen. Es erm\u00f6glicht den Datenaustausch, erleichtert die Zusammenarbeit und verbessert die betriebliche Effizienz.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> k\u00f6nnen miteinander kommunizieren, indem sie ihre Namen als Hostnamen verwenden. Dies eliminiert die Notwendigkeit statischer Links.<\/p>\n<\/li>\n<li>\n<p><strong>Isolation<\/strong>: User-defined networks allow you to isolate groups of containers from one another, enhancing security and organization.<\/p>\n<\/li>\n<li>\n<p><strong>Dynamic Configuration<\/strong>: You can <span class=\"glossaryai-tooltip glossary-term-674\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/add\/\" target=\"_blank\">add<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Die ADD-Anweisung in Docker ist ein Befehl, der in Dockerfiles verwendet wird, um Dateien und Verzeichnisse von einem Host-Computer in ein Docker-Image w\u00e4hrend des Build-Prozesses zu kopieren. Sie erm\u00f6glicht nicht nur den Transfer lokaler Dateien, sondern bietet auch zus\u00e4tzliche Funktionen, wie das automatische Extrahieren komprimierter Dateien und das Abrufen von Remote-Dateien \u00fcber HTTP oder HTTPS.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/add\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> or remove containers from a <span class=\"glossaryai-tooltip glossary-term-661\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\" target=\"_blank\">network<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Ein Netzwerk im Bereich der Informatik bezeichnet eine Sammlung miteinander verbundener Ger\u00e4te, die miteinander kommunizieren und Ressourcen teilen. Es erm\u00f6glicht den Datenaustausch, erleichtert die Zusammenarbeit und verbessert die betriebliche Effizienz.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> without needing to recreate existing ones, providing a more flexible infrastructure.<\/p>\n<\/li>\n<li>\n<p><strong>DNS-Aufl\u00f6sung<\/strong>: Docker provides built-in DNS resolution for containers on the same <span class=\"glossaryai-tooltip glossary-term-661\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\" target=\"_blank\">network<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Ein Netzwerk im Bereich der Informatik bezeichnet eine Sammlung miteinander verbundener Ger\u00e4te, die miteinander kommunizieren und Ressourcen teilen. Es erm\u00f6glicht den Datenaustausch, erleichtert die Zusammenarbeit und verbessert die betriebliche Effizienz.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span>, making it easy to reference them by name.<\/p>\n<\/li>\n<\/ol>\n<h3>Erstellen eines benutzerdefinierten Netzwerks<\/h3>\n<p>To create a user-defined <span class=\"glossaryai-tooltip glossary-term-661\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\" target=\"_blank\">network<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Ein Netzwerk im Bereich der Informatik bezeichnet eine Sammlung miteinander verbundener Ger\u00e4te, die miteinander kommunizieren und Ressourcen teilen. Es erm\u00f6glicht den Datenaustausch, erleichtert die Zusammenarbeit und verbessert die betriebliche Effizienz.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span>, Sie k\u00f6nnen den folgenden Befehl verwenden:<\/p>\n<pre><code class=\"language-bash\"><span class=\"glossaryai-tooltip glossary-term-1163\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/docker-network-create\/\" target=\"_blank\">docker network create<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Der Befehl `docker network create` erm\u00f6glicht es Benutzern, benutzerdefinierte Netzwerke f\u00fcr containerisierte Anwendungen einzurichten. Dies erleichtert eine effiziente Kommunikation und Isolation zwischen Containern und verbessert so die Leistung und Sicherheit der Anwendung.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/docker-network-create\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> my_network<\/code><\/pre>\n<p>After creating the <span class=\"glossaryai-tooltip glossary-term-661\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\" target=\"_blank\">network<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Ein Netzwerk im Bereich der Informatik bezeichnet eine Sammlung miteinander verbundener Ger\u00e4te, die miteinander kommunizieren und Ressourcen teilen. Es erm\u00f6glicht den Datenaustausch, erleichtert die Zusammenarbeit und verbessert die betriebliche Effizienz.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span>, you can <span class=\"glossaryai-tooltip glossary-term-672\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/run\/\" target=\"_blank\">laufen<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">\"RUN\" bezeichnet einen Befehl in verschiedenen Programmiersprachen und Betriebssystemen, um ein angegebenes Programm oder Skript auszuf\u00fchren. Er initiiert Prozesse und stellt eine kontrollierte Ausf\u00fchrungsumgebung f\u00fcr die Aufgabenbereitstellung bereit.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/run\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> containers connected to it:<\/p>\n<pre><code class=\"language-bash\">docker <span class=\"glossaryai-tooltip glossary-term-672\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/run\/\" target=\"_blank\">laufen<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">\"RUN\" bezeichnet einen Befehl in verschiedenen Programmiersprachen und Betriebssystemen, um ein angegebenes Programm oder Skript auszuf\u00fchren. Er initiiert Prozesse und stellt eine kontrollierte Ausf\u00fchrungsumgebung f\u00fcr die Aufgabenbereitstellung bereit.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/run\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> -d --name my_db --network my_network mysql\ndocker <span class=\"glossaryai-tooltip glossary-term-672\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/run\/\" target=\"_blank\">laufen<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">\"RUN\" bezeichnet einen Befehl in verschiedenen Programmiersprachen und Betriebssystemen, um ein angegebenes Programm oder Skript auszuf\u00fchren. Er initiiert Prozesse und stellt eine kontrollierte Ausf\u00fchrungsumgebung f\u00fcr die Aufgabenbereitstellung bereit.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/run\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> -d --name my_app --network my_network my_app_image<\/code><\/pre>\n<p>Now, <code>my_app<\/code> kann mit ... kommunizieren <code>my_db<\/code> mit dem Hostnamen <code>my_db<\/code>.<\/p>\n<h2>Netzwerkmodi in Docker<\/h2>\n<p>Docker supports several networking modes, each suitable for different scenarios. Understanding these modes can help you choose the right one for your application:<\/p>\n<h3>1. <strong>Br\u00fcckenmodus (Standard)<\/strong><\/h3>\n<p>Docker&#8217;s default networking mode is the bridge mode. It creates a private internal <span class=\"glossaryai-tooltip glossary-term-661\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\" target=\"_blank\">network<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Ein Netzwerk im Bereich der Informatik bezeichnet eine Sammlung miteinander verbundener Ger\u00e4te, die miteinander kommunizieren und Ressourcen teilen. Es erm\u00f6glicht den Datenaustausch, erleichtert die Zusammenarbeit und verbessert die betriebliche Effizienz.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> on your host, and containers running in this mode can communicate with each other using IP addresses or <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> names.<\/p>\n<h3>2. <strong>Host-Modus<\/strong><\/h3>\n<p>In host mode, the <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> shares the host&#8217;s networking <span class=\"glossaryai-tooltip glossary-term-682\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/stack\/\" target=\"_blank\">stack<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Ein Stapel (Stack) ist eine Datenstruktur, die nach dem Last-In-First-Out-Prinzip (LIFO) arbeitet, bei dem das zuletzt hinzugef\u00fcgte Element als erstes entfernt wird. Er unterst\u00fctzt zwei prim\u00e4re Operationen: Einf\u00fcgen (push) und Entfernen (pop).<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/stack\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span>. This means that the <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> will use the host&#8217;s IP address, eliminating <span class=\"glossaryai-tooltip glossary-term-661\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\" target=\"_blank\">network<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Ein Netzwerk im Bereich der Informatik bezeichnet eine Sammlung miteinander verbundener Ger\u00e4te, die miteinander kommunizieren und Ressourcen teilen. Es erm\u00f6glicht den Datenaustausch, erleichtert die Zusammenarbeit und verbessert die betriebliche Effizienz.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> latency but potentially resulting in <span class=\"glossaryai-tooltip glossary-term-677\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/port\/\" target=\"_blank\">port<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Ein PORT ist ein Kommunikationsendpunkt in einem Computernetzwerk, der durch eine numerische Kennung definiert ist. Er erm\u00f6glicht die Weiterleitung von Daten an bestimmte Anwendungen und verbessert so die Funktionalit\u00e4t und Sicherheit des Systems.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/port\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> conflicts. This mode is useful for performance-sensitive applications.<\/p>\n<pre><code class=\"language-bash\">docker <span class=\"glossaryai-tooltip glossary-term-672\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/run\/\" target=\"_blank\">laufen<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">\"RUN\" bezeichnet einen Befehl in verschiedenen Programmiersprachen und Betriebssystemen, um ein angegebenes Programm oder Skript auszuf\u00fchren. Er initiiert Prozesse und stellt eine kontrollierte Ausf\u00fchrungsumgebung f\u00fcr die Aufgabenbereitstellung bereit.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/run\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> --network host my_app_image<\/code><\/pre>\n<h3>3. <strong>Kein Modus<\/strong><\/h3>\n<p>When using the none mode, the <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> will not have its own <span class=\"glossaryai-tooltip glossary-term-661\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\" target=\"_blank\">network<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Ein Netzwerk im Bereich der Informatik bezeichnet eine Sammlung miteinander verbundener Ger\u00e4te, die miteinander kommunizieren und Ressourcen teilen. Es erm\u00f6glicht den Datenaustausch, erleichtert die Zusammenarbeit und verbessert die betriebliche Effizienz.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> interface, isolating it completely from any <span class=\"glossaryai-tooltip glossary-term-661\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\" target=\"_blank\">network<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Ein Netzwerk im Bereich der Informatik bezeichnet eine Sammlung miteinander verbundener Ger\u00e4te, die miteinander kommunizieren und Ressourcen teilen. Es erm\u00f6glicht den Datenaustausch, erleichtert die Zusammenarbeit und verbessert die betriebliche Effizienz.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span>. This can be beneficial for security-sensitive applications.<\/p>\n<pre><code class=\"language-bash\">docker <span class=\"glossaryai-tooltip glossary-term-672\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/run\/\" target=\"_blank\">laufen<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">\"RUN\" bezeichnet einen Befehl in verschiedenen Programmiersprachen und Betriebssystemen, um ein angegebenes Programm oder Skript auszuf\u00fchren. Er initiiert Prozesse und stellt eine kontrollierte Ausf\u00fchrungsumgebung f\u00fcr die Aufgabenbereitstellung bereit.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/run\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> --network none my_app_image<\/code><\/pre>\n<h3>4. <strong>\u00dcberlagerungsmodus<\/strong><\/h3>\n<p>Overlay networks allow containers running on different Docker hosts to communicate with each other. This is particularly useful for multi-host deployments, like those orchestrated with <span class=\"glossaryai-tooltip glossary-term-655\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/docker-swarm\/\" target=\"_blank\">Docker Swarm<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Docker Swarm is a container orchestration tool that enables the management of a cluster of Docker engines. It simplifies scaling and deployment, ensuring high availability and load balancing across services.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/docker-swarm\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> or <span class=\"glossaryai-tooltip glossary-term-656\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/kubernetes\/\" target=\"_blank\">Kubernetes<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Kubernetes ist eine Open-Source-Plattform zur Container-Orchestrierung, die die Bereitstellung, Skalierung und Verwaltung von containerisierten Anwendungen automatisiert und so die Ressourceneffizienz und Resilienz verbessert.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/kubernetes\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span>.<\/p>\n<pre><code class=\"language-bash\"><span class=\"glossaryai-tooltip glossary-term-1163\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/docker-network-create\/\" target=\"_blank\">docker network create<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Der Befehl `docker network create` erm\u00f6glicht es Benutzern, benutzerdefinierte Netzwerke f\u00fcr containerisierte Anwendungen einzurichten. Dies erleichtert eine effiziente Kommunikation und Isolation zwischen Containern und verbessert so die Leistung und Sicherheit der Anwendung.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/docker-network-create\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> -d overlay my_overlay_network<\/code><\/pre>\n<h2>Fortgeschrittene Techniken f\u00fcr die Container-Kommunikation<\/h2>\n<p>Beyond basic linking and user-defined networks, there are various advanced techniques you can use to facilitate communication between Docker containers.<\/p>\n<h3>Service Discovery mit Docker Compose<\/h3>\n<p><span class=\"glossaryai-tooltip glossary-term-654\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/docker-compose\/\" target=\"_blank\">Docker Compose<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Docker Compose ist ein Werkzeug zur Definition und Ausf\u00fchrung von Multi-Container-Docker-Anwendungen mithilfe einer YAML-Datei. Es vereinfacht die Bereitstellung, Konfiguration und Orchestrierung von Diensten und verbessert die Entwicklungseffizienz.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/docker-compose\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> is a tool for defining and running multi-container Docker applications. It allows you to define services in a <code>docker-compose.yml<\/code> Datei, was es einfach macht, Beziehungen zwischen Containern zu verwalten.<\/p>\n<pre><code class=\"language-yaml\">version: '3'\nservices:\n  db:\n    <span class=\"glossaryai-tooltip glossary-term-651\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/image\/\" target=\"_blank\">Bild<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Ein Bild ist eine visuelle Darstellung eines Objekts oder einer Szene, die typischerweise aus Pixeln in digitalen Formaten besteht. Es kann Informationen vermitteln, Emotionen hervorrufen und die Kommunikation \u00fcber verschiedene Medien hinweg erleichtern.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/image\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span>: mysql\n    environment:\n      MYSQL_ROOT_PASSWORD: root\n  web:\n    <span class=\"glossaryai-tooltip glossary-term-651\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/image\/\" target=\"_blank\">Bild<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Ein Bild ist eine visuelle Darstellung eines Objekts oder einer Szene, die typischerweise aus Pixeln in digitalen Formaten besteht. Es kann Informationen vermitteln, Emotionen hervorrufen und die Kommunikation \u00fcber verschiedene Medien hinweg erleichtern.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/image\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span>: my_app_image\n    depends_on:\n      - db<\/code><\/pre>\n<p>In diesem Beispiel <code>Netz<\/code> <span class=\"glossaryai-tooltip glossary-term-681\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/service\/\" target=\"_blank\">Service<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Service bezeichnet die Handlung, Unterst\u00fctzung oder Hilfe zu leisten, um spezifische Bed\u00fcrfnisse oder Anforderungen zu erf\u00fcllen. In verschiedenen Bereichen umfasst er Kundenservice, technischen Support und professionelle Dienstleistungen, wobei Effizienz und Nutzerzufriedenheit im Vordergrund stehen.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/service\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> can communicate with the <code>db<\/code> <span class=\"glossaryai-tooltip glossary-term-681\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/service\/\" target=\"_blank\">Service<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Service bezeichnet die Handlung, Unterst\u00fctzung oder Hilfe zu leisten, um spezifische Bed\u00fcrfnisse oder Anforderungen zu erf\u00fcllen. In verschiedenen Bereichen umfasst er Kundenservice, technischen Support und professionelle Dienstleistungen, wobei Effizienz und Nutzerzufriedenheit im Vordergrund stehen.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/service\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> mit dem Hostnamen <code>db<\/code>.<\/p>\n<h3>Using API Gateway<\/h3>\n<p>In microservices architectures, using an <span class=\"glossaryai-tooltip glossary-term-1249\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/api\/\" target=\"_blank\">API<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Eine API, oder Anwendungsprogrammierschnittstelle, erm\u00f6glicht es Softwareanwendungen, miteinander zu kommunizieren und zu interagieren. Sie definiert Protokolle und Werkzeuge f\u00fcr die Entwicklung von Software und die Erleichterung der Integration.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/api\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> Gateway kann die Kommunikation zwischen Diensten optimieren. Tools wie Kong oder Traefik k\u00f6nnen Anfragen zwischen verschiedenen Containern basierend auf definierten Regeln weiterleiten und so Sicherheit und Verwaltbarkeit verbessern.<\/p>\n<h3>Lastenausgleich<\/h3>\n<p>For applications requiring high availability, <span class=\"glossaryai-tooltip glossary-term-697\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/load-balancing\/\" target=\"_blank\">Lastverteilung<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Lastausgleich ist eine entscheidende Netzwerkmanagement-Technik, die eingehenden Datenverkehr auf mehrere Server verteilt. Dies gew\u00e4hrleistet eine optimale Ressourcennutzung, minimiert die Antwortzeit und verbessert die Verf\u00fcgbarkeit von Anwendungen.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/load-balancing\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> between containers is crucial. <span class=\"glossaryai-tooltip glossary-term-655\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/docker-swarm\/\" target=\"_blank\">Docker Swarm<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Docker Swarm is a container orchestration tool that enables the management of a cluster of Docker engines. It simplifies scaling and deployment, ensuring high availability and load balancing across services.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/docker-swarm\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> provides built-in <span class=\"glossaryai-tooltip glossary-term-697\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/load-balancing\/\" target=\"_blank\">Lastverteilung<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Lastausgleich ist eine entscheidende Netzwerkmanagement-Technik, die eingehenden Datenverkehr auf mehrere Server verteilt. Dies gew\u00e4hrleistet eine optimale Ressourcennutzung, minimiert die Antwortzeit und verbessert die Verf\u00fcgbarkeit von Anwendungen.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/load-balancing\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span>, ensuring uniform distribution of traffic across containers.<\/p>\n<h3>Message Queues<\/h3>\n<p>Die Verwendung von Message-Queuing-Systemen wie RabbitMQ oder Kafka kann Dienste entkoppeln und die Widerstandsf\u00e4higkeit verbessern. Anstatt einer direkten Kommunikation ver\u00f6ffentlichen Container Nachrichten in Warteschlangen, was eine asynchrone Verarbeitung erm\u00f6glicht.<\/p>\n<h2>Troubleshooting Container Communication Issues<\/h2>\n<p>Even with the best configurations, you might encounter communication issues between containers. Here are some common troubleshooting steps:<\/p>\n<h3>1. <strong>\u00dcberpr\u00fcfen <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Container<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> Status<\/strong><\/h3>\n<p>Ensure that all containers involved are running and healthy. Use <code>docker ps<\/code> to check the status of your containers.<\/p>\n<h3>2. <strong><span class=\"glossaryai-tooltip glossary-term-661\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\" target=\"_blank\">Netzwerk<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Ein Netzwerk im Bereich der Informatik bezeichnet eine Sammlung miteinander verbundener Ger\u00e4te, die miteinander kommunizieren und Ressourcen teilen. Es erm\u00f6glicht den Datenaustausch, erleichtert die Zusammenarbeit und verbessert die betriebliche Effizienz.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> Connectivity<\/strong><\/h3>\n<p>Check that the containers are on the same <span class=\"glossaryai-tooltip glossary-term-661\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\" target=\"_blank\">network<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Ein Netzwerk im Bereich der Informatik bezeichnet eine Sammlung miteinander verbundener Ger\u00e4te, die miteinander kommunizieren und Ressourcen teilen. Es erm\u00f6glicht den Datenaustausch, erleichtert die Zusammenarbeit und verbessert die betriebliche Effizienz.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span>. You can inspect your <span class=\"glossaryai-tooltip glossary-term-661\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\" target=\"_blank\">network<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Ein Netzwerk im Bereich der Informatik bezeichnet eine Sammlung miteinander verbundener Ger\u00e4te, die miteinander kommunizieren und Ressourcen teilen. Es erm\u00f6glicht den Datenaustausch, erleichtert die Zusammenarbeit und verbessert die betriebliche Effizienz.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> mit:<\/p>\n<pre><code class=\"language-bash\"><span class=\"glossaryai-tooltip glossary-term-1164\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/docker-network-inspect\/\" target=\"_blank\">docker Netzwerk untersuchen<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Docker Network Inspect bietet detaillierte Einblicke in die Konfiguration eines Docker-Netzwerks und die verbundenen Container. Dieser Befehl ist unerl\u00e4sslich f\u00fcr die Fehlerbehebung bei Netzwerkproblemen und die Optimierung der Container-Kommunikation.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/docker-network-inspect\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> my_network<\/code><\/pre>\n<h3>3. <strong>Firewall Rules<\/strong><\/h3>\n<p>Stellen Sie sicher, dass die Firewall-Regeln auf dem Host-Computer die Kommunikation zwischen Containern nicht blockieren.<\/p>\n<h3>4. <strong><span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Container<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> Logs<\/strong><\/h3>\n<p>Untersuchen Sie die Protokolle beider Container auf Fehler oder Probleme, die darauf hindeuten k\u00f6nnten, warum sie nicht kommunizieren k\u00f6nnen.<\/p>\n<pre><code class=\"language-bash\">docker logs my_app<\/code><\/pre>\n<h2>Fazit<\/h2>\n<p>Linking Docker containers is a vital aspect of building microservices and containerized applications. While the traditional method of linking is largely deprecated in favor of user-defined networks, understanding both approaches is essential for navigating the evolving landscape of containerization. By leveraging advanced networking techniques such as <span class=\"glossaryai-tooltip glossary-term-654\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/docker-compose\/\" target=\"_blank\">Docker Compose<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Docker Compose ist ein Werkzeug zur Definition und Ausf\u00fchrung von Multi-Container-Docker-Anwendungen mithilfe einer YAML-Datei. Es vereinfacht die Bereitstellung, Konfiguration und Orchestrierung von Diensten und verbessert die Entwicklungseffizienz.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/docker-compose\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span>, <span class=\"glossaryai-tooltip glossary-term-1249\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/api\/\" target=\"_blank\">API<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Eine API, oder Anwendungsprogrammierschnittstelle, erm\u00f6glicht es Softwareanwendungen, miteinander zu kommunizieren und zu interagieren. Sie definiert Protokolle und Werkzeuge f\u00fcr die Entwicklung von Software und die Erleichterung der Integration.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/api\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> gateways, and message queues, developers can create resilient, scalable architectures that facilitate seamless communication between containers.<\/p>\n<p>With continuous advancements in <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> technology and <span class=\"glossaryai-tooltip glossary-term-657\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/orchestration\/\" target=\"_blank\">Orchestrierung<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Orchestrierung bezieht sich auf die automatisierte Verwaltung und Koordination komplexer Systeme und Dienstleistungen. Sie optimiert Prozesse durch die Integration verschiedener Komponenten und gew\u00e4hrleistet so einen effizienten Betrieb und eine optimale Ressourcennutzung.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/orchestration\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span>, it&#8217;s essential to stay informed and adapt to best practices to make the most out of the Docker platform. Whether you&#8217;re building a simple application or a complex microservices architecture, mastering <span class=\"glossaryai-tooltip glossary-term-650\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\" target=\"_blank\">Beh\u00e4lter<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Containers are lightweight, portable units that encapsulate software and its dependencies, enabling consistent execution across different environments. They leverage OS-level virtualization for efficiency.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/container\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> communication is key to unlocking the full potential of your Dockerized applications.<\/p>","protected":false},"excerpt":{"rendered":"<p>Docker-Container verkn\u00fcpfen, damit sie nahtlos miteinander kommunizieren k\u00f6nnen. Verwenden Sie beim Starten von Containern das `\u2013link`-Flag oder nutzen Sie... <span class=\"glossaryai-tooltip glossary-term-654\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/docker-compose\/\" target=\"_blank\">Docker Compose<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Docker Compose ist ein Werkzeug zur Definition und Ausf\u00fchrung von Multi-Container-Docker-Anwendungen mithilfe einer YAML-Datei. Es vereinfacht die Bereitstellung, Konfiguration und Orchestrierung von Diensten und verbessert die Entwicklungseffizienz.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/docker-compose\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> f\u00fcr <span class=\"glossaryai-tooltip glossary-term-661\"><span class=\"glossaryai-link\"><a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\" target=\"_blank\">network<\/a><\/span><span class=\"gai-content-hidden glossaryai-tooltip-content\"><span class=\"gai-tooltip-body\"><span class=\"glossaryai-tooltip-text\">Ein Netzwerk im Bereich der Informatik bezeichnet eine Sammlung miteinander verbundener Ger\u00e4te, die miteinander kommunizieren und Ressourcen teilen. Es erm\u00f6glicht den Datenaustausch, erleichtert die Zusammenarbeit und verbessert die betriebliche Effizienz.<span class=\"glossaryai-more-link\"> <a href=\"https:\/\/dockerpros.com\/de\/wiki\/network\/\">More \u00bb<\/a><\/span><\/span><\/span><\/span><\/span> Konfiguration.<\/p>","protected":false},"author":1,"featured_media":356,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-190","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-container-creation-and-management"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How do I link Docker containers? - Dockerpros<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dockerpros.com\/de\/container-creation-and-management\/so-verknupfen-sie-docker-containerdie-veraltete-methode-mit-link-wird-nicht-mehr-empfohlen-verwenden-sie-stattdessen-benutzerdefinierte-docker-netzwerke1-netzwerk-erstellen-bash\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How do I link Docker containers? - Dockerpros\" \/>\n<meta property=\"og:description\" content=\"Linking Docker containers allows them to communicate seamlessly. Use the `--link` flag when starting containers, or leverage Docker Compose for network configuration.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dockerpros.com\/de\/container-creation-and-management\/so-verknupfen-sie-docker-containerdie-veraltete-methode-mit-link-wird-nicht-mehr-empfohlen-verwenden-sie-stattdessen-benutzerdefinierte-docker-netzwerke1-netzwerk-erstellen-bash\/\" \/>\n<meta property=\"og:site_name\" content=\"Dockerpros\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-21T11:50:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dockerpros.com\/wp-content\/uploads\/2024\/07\/how-do-i-link-docker-containers_190.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"dockerpros\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"dockerpros\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/\"},\"author\":{\"name\":\"dockerpros\",\"@id\":\"https:\/\/dockerpros.com\/#\/schema\/person\/a9b4c3d7f7a8e2b072e77d47b382a3a4\"},\"headline\":\"How do I link Docker containers?\",\"datePublished\":\"2024-07-21T11:50:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/\"},\"wordCount\":1091,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dockerpros.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dockerpros.com\/wp-content\/uploads\/2024\/07\/how-do-i-link-docker-containers_190.jpg\",\"articleSection\":[\"Container Creation and Management\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/\",\"url\":\"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/\",\"name\":\"How do I link Docker containers? - Dockerpros\",\"isPartOf\":{\"@id\":\"https:\/\/dockerpros.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dockerpros.com\/wp-content\/uploads\/2024\/07\/how-do-i-link-docker-containers_190.jpg\",\"datePublished\":\"2024-07-21T11:50:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/#primaryimage\",\"url\":\"https:\/\/dockerpros.com\/wp-content\/uploads\/2024\/07\/how-do-i-link-docker-containers_190.jpg\",\"contentUrl\":\"https:\/\/dockerpros.com\/wp-content\/uploads\/2024\/07\/how-do-i-link-docker-containers_190.jpg\",\"width\":800,\"height\":600,\"caption\":\"how-do-i-link-docker-containers-2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dockerpros.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"How do I link Docker containers?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dockerpros.com\/#website\",\"url\":\"https:\/\/dockerpros.com\/\",\"name\":\"Dockerpros\",\"description\":\"DockerPros \u2013 Your Ultimate Docker Resource Hub\",\"publisher\":{\"@id\":\"https:\/\/dockerpros.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dockerpros.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dockerpros.com\/#organization\",\"name\":\"Dockerpros\",\"url\":\"https:\/\/dockerpros.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dockerpros.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dockerpros.com\/wp-content\/uploads\/2024\/07\/Dockerpros_logo_blanco.png\",\"contentUrl\":\"https:\/\/dockerpros.com\/wp-content\/uploads\/2024\/07\/Dockerpros_logo_blanco.png\",\"width\":532,\"height\":114,\"caption\":\"Dockerpros\"},\"image\":{\"@id\":\"https:\/\/dockerpros.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dockerpros.com\/#\/schema\/person\/a9b4c3d7f7a8e2b072e77d47b382a3a4\",\"name\":\"dockerpros\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/dockerpros.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dockerpros.com\/wp-content\/litespeed\/avatar\/d13b9d4f101de1a7535b404e0c59affd.jpg?ver=1783601465\",\"contentUrl\":\"https:\/\/dockerpros.com\/wp-content\/litespeed\/avatar\/d13b9d4f101de1a7535b404e0c59affd.jpg?ver=1783601465\",\"caption\":\"dockerpros\"},\"sameAs\":[\"https:\/\/dockerpros.com\/\"],\"url\":\"https:\/\/dockerpros.com\/de\/author\/dockerpros\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie verbinde ich Docker-Container? - Dockerpros\n\nDocker ist eine Open-Source-Plattform, die es Entwicklern erm\u00f6glicht, Anwendungen in Containern zu erstellen, bereitzustellen und auszuf\u00fchren. Container sind leichtgewichtige, eigenst\u00e4ndige ausf\u00fchrbare Pakete, die alles enthalten, was eine Anwendung zum Ausf\u00fchren ben\u00f6tigt, einschlie\u00dflich Code, Laufzeit, Systemtools, Systembibliotheken und Einstellungen. Docker-Container sind portabel und k\u00f6nnen auf jeder Plattform ausgef\u00fchrt werden, die Docker unterst\u00fctzt.\n\nDocker-Container k\u00f6nnen auf verschiedene Weise miteinander verbunden werden. Die gebr\u00e4uchlichste Methode ist die Verwendung von Docker-Netzwerken. Docker-Netzwerke erm\u00f6glichen es Containern, miteinander zu kommunizieren und Ressourcen zu teilen. Es gibt drei Arten von Docker-Netzwerken: Bridge, Host und None.\n\nBridge-Netzwerke sind das Standardnetzwerk f\u00fcr Docker-Container. Wenn Sie einen Container erstellen, wird er automatisch mit dem Bridge-Netzwerk verbunden. Bridge-Netzwerke erm\u00f6glichen es Containern, miteinander zu kommunizieren und Ressourcen zu teilen. Sie k\u00f6nnen auch benutzerdefinierte Bridge-Netzwerke erstellen, um die Kommunikation zwischen Containern zu steuern.\n\nHost-Netzwerke erm\u00f6glichen es Containern, direkt mit dem Host-Betriebssystem zu kommunizieren. Dies ist n\u00fctzlich, wenn Sie einen Container ausf\u00fchren m\u00f6chten, der auf das Netzwerk des Host-Systems zugreifen muss.\n\nNone-Netzwerke erm\u00f6glichen es Containern, ohne Netzwerkkonnektivit\u00e4t zu laufen. Dies ist n\u00fctzlich, wenn Sie einen Container ausf\u00fchren m\u00f6chten, der keine Netzwerkverbindung ben\u00f6tigt.\n\nEine weitere M\u00f6glichkeit, Docker-Container zu verbinden, ist die Verwendung von Docker-Links. Docker-Links erm\u00f6glichen es Containern, miteinander zu kommunizieren, indem sie Umgebungsvariablen und DNS-Eintr\u00e4ge verwenden. Docker-Links sind jedoch veraltet und werden nicht mehr empfohlen.\n\nEine dritte M\u00f6glichkeit, Docker-Container zu verbinden, ist die Verwendung von Docker Compose. Docker Compose ist ein Tool, das es Entwicklern erm\u00f6glicht, mehrere Container als eine einzige Anwendung zu definieren und auszuf\u00fchren. Docker Compose verwendet eine YAML-Datei, um die Konfiguration der Container zu definieren.\n\nUm Docker-Container mit Docker-Netzwerken zu verbinden, m\u00fcssen Sie zuerst ein Netzwerk erstellen. Sie k\u00f6nnen ein Netzwerk mit dem folgenden Befehl erstellen:\n\n```\ndocker network create my-network\n```\n\nSobald Sie ein Netzwerk erstellt haben, k\u00f6nnen Sie Container mit diesem Netzwerk verbinden. Sie k\u00f6nnen einen Container mit dem folgenden Befehl mit einem Netzwerk verbinden:\n\n```\ndocker run -d --name my-container --network my-network my-image\n```\n\nIn diesem Beispiel wird ein Container mit dem Namen \"my-container\" aus dem Image \"my-image\" erstellt und mit dem Netzwerk \"my-network\" verbunden.\n\nUm Docker-Container mit Docker Compose zu verbinden, m\u00fcssen Sie zuerst eine YAML-Datei erstellen, die die Konfiguration der Container definiert. Hier ist ein Beispiel f\u00fcr eine YAML-Datei, die zwei Container definiert, die miteinander verbunden sind:\n\n```\nversion: '3'\nservices:\n  web:\n    image: my-web-image\n    ports:\n      - \"8080:8080\"\n    depends_on:\n      - db\n  db:\n    image: my-db-image\n    environment:\n      MYSQL_ROOT_PASSWORD: my-password\n```\n\nIn diesem Beispiel werden zwei Container definiert: \"web\" und \"db\". Der \"web\"-Container verwendet das Image \"my-web-image\" und ist auf Port 8080 verf\u00fcgbar. Der \"db\"-Container verwendet das Image \"my-db-image\" und hat eine Umgebungsvariable \"MYSQL_ROOT_PASSWORD\" mit dem Wert \"my-password\". Der \"web\"-Container h\u00e4ngt vom \"db\"-Container ab, was bedeutet, dass der \"db\"-Container gestartet wird, bevor der \"web\"-Container gestartet wird.\n\nUm die Container mit Docker Compose zu starten, verwenden Sie den folgenden Befehl:\n\n```\ndocker-compose up\n```\n\nZusammenfassend l\u00e4sst sich sagen, dass es mehrere M\u00f6glichkeiten gibt, Docker-Container zu verbinden. Die gebr\u00e4uchlichste Methode ist die Verwendung von Docker-Netzwerken. Docker-Netzwerke erm\u00f6glichen es Containern, miteinander zu kommunizieren und Ressourcen zu teilen. Sie k\u00f6nnen auch benutzerdefinierte Bridge-Netzwerke erstellen, um die Kommunikation zwischen Containern zu steuern. Docker-Links sind veraltet und werden nicht mehr empfohlen. Docker Compose ist ein Tool, das es Entwicklern erm\u00f6glicht, mehrere Container als eine einzige Anwendung zu definieren und auszuf\u00fchren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dockerpros.com\/de\/container-creation-and-management\/so-verknupfen-sie-docker-containerdie-veraltete-methode-mit-link-wird-nicht-mehr-empfohlen-verwenden-sie-stattdessen-benutzerdefinierte-docker-netzwerke1-netzwerk-erstellen-bash\/","og_locale":"de_DE","og_type":"article","og_title":"How do I link Docker containers? - Dockerpros","og_description":"Linking Docker containers allows them to communicate seamlessly. Use the `--link` flag when starting containers, or leverage Docker Compose for network configuration.","og_url":"https:\/\/dockerpros.com\/de\/container-creation-and-management\/so-verknupfen-sie-docker-containerdie-veraltete-methode-mit-link-wird-nicht-mehr-empfohlen-verwenden-sie-stattdessen-benutzerdefinierte-docker-netzwerke1-netzwerk-erstellen-bash\/","og_site_name":"Dockerpros","article_published_time":"2024-07-21T11:50:52+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/dockerpros.com\/wp-content\/uploads\/2024\/07\/how-do-i-link-docker-containers_190.jpg","type":"image\/jpeg"}],"author":"dockerpros","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"dockerpros","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/#article","isPartOf":{"@id":"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/"},"author":{"name":"dockerpros","@id":"https:\/\/dockerpros.com\/#\/schema\/person\/a9b4c3d7f7a8e2b072e77d47b382a3a4"},"headline":"How do I link Docker containers?","datePublished":"2024-07-21T11:50:52+00:00","mainEntityOfPage":{"@id":"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/"},"wordCount":1091,"commentCount":0,"publisher":{"@id":"https:\/\/dockerpros.com\/#organization"},"image":{"@id":"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/#primaryimage"},"thumbnailUrl":"https:\/\/dockerpros.com\/wp-content\/uploads\/2024\/07\/how-do-i-link-docker-containers_190.jpg","articleSection":["Container Creation and Management"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/","url":"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/","name":"Wie verbinde ich Docker-Container? - Dockerpros\n\nDocker ist eine Open-Source-Plattform, die es Entwicklern erm\u00f6glicht, Anwendungen in Containern zu erstellen, bereitzustellen und auszuf\u00fchren. Container sind leichtgewichtige, eigenst\u00e4ndige ausf\u00fchrbare Pakete, die alles enthalten, was eine Anwendung zum Ausf\u00fchren ben\u00f6tigt, einschlie\u00dflich Code, Laufzeit, Systemtools, Systembibliotheken und Einstellungen. Docker-Container sind portabel und k\u00f6nnen auf jeder Plattform ausgef\u00fchrt werden, die Docker unterst\u00fctzt.\n\nDocker-Container k\u00f6nnen auf verschiedene Weise miteinander verbunden werden. Die gebr\u00e4uchlichste Methode ist die Verwendung von Docker-Netzwerken. Docker-Netzwerke erm\u00f6glichen es Containern, miteinander zu kommunizieren und Ressourcen zu teilen. Es gibt drei Arten von Docker-Netzwerken: Bridge, Host und None.\n\nBridge-Netzwerke sind das Standardnetzwerk f\u00fcr Docker-Container. Wenn Sie einen Container erstellen, wird er automatisch mit dem Bridge-Netzwerk verbunden. Bridge-Netzwerke erm\u00f6glichen es Containern, miteinander zu kommunizieren und Ressourcen zu teilen. Sie k\u00f6nnen auch benutzerdefinierte Bridge-Netzwerke erstellen, um die Kommunikation zwischen Containern zu steuern.\n\nHost-Netzwerke erm\u00f6glichen es Containern, direkt mit dem Host-Betriebssystem zu kommunizieren. Dies ist n\u00fctzlich, wenn Sie einen Container ausf\u00fchren m\u00f6chten, der auf das Netzwerk des Host-Systems zugreifen muss.\n\nNone-Netzwerke erm\u00f6glichen es Containern, ohne Netzwerkkonnektivit\u00e4t zu laufen. Dies ist n\u00fctzlich, wenn Sie einen Container ausf\u00fchren m\u00f6chten, der keine Netzwerkverbindung ben\u00f6tigt.\n\nEine weitere M\u00f6glichkeit, Docker-Container zu verbinden, ist die Verwendung von Docker-Links. Docker-Links erm\u00f6glichen es Containern, miteinander zu kommunizieren, indem sie Umgebungsvariablen und DNS-Eintr\u00e4ge verwenden. Docker-Links sind jedoch veraltet und werden nicht mehr empfohlen.\n\nEine dritte M\u00f6glichkeit, Docker-Container zu verbinden, ist die Verwendung von Docker Compose. Docker Compose ist ein Tool, das es Entwicklern erm\u00f6glicht, mehrere Container als eine einzige Anwendung zu definieren und auszuf\u00fchren. Docker Compose verwendet eine YAML-Datei, um die Konfiguration der Container zu definieren.\n\nUm Docker-Container mit Docker-Netzwerken zu verbinden, m\u00fcssen Sie zuerst ein Netzwerk erstellen. Sie k\u00f6nnen ein Netzwerk mit dem folgenden Befehl erstellen:\n\n```\ndocker network create my-network\n```\n\nSobald Sie ein Netzwerk erstellt haben, k\u00f6nnen Sie Container mit diesem Netzwerk verbinden. Sie k\u00f6nnen einen Container mit dem folgenden Befehl mit einem Netzwerk verbinden:\n\n```\ndocker run -d --name my-container --network my-network my-image\n```\n\nIn diesem Beispiel wird ein Container mit dem Namen \"my-container\" aus dem Image \"my-image\" erstellt und mit dem Netzwerk \"my-network\" verbunden.\n\nUm Docker-Container mit Docker Compose zu verbinden, m\u00fcssen Sie zuerst eine YAML-Datei erstellen, die die Konfiguration der Container definiert. Hier ist ein Beispiel f\u00fcr eine YAML-Datei, die zwei Container definiert, die miteinander verbunden sind:\n\n```\nversion: '3'\nservices:\n  web:\n    image: my-web-image\n    ports:\n      - \"8080:8080\"\n    depends_on:\n      - db\n  db:\n    image: my-db-image\n    environment:\n      MYSQL_ROOT_PASSWORD: my-password\n```\n\nIn diesem Beispiel werden zwei Container definiert: \"web\" und \"db\". Der \"web\"-Container verwendet das Image \"my-web-image\" und ist auf Port 8080 verf\u00fcgbar. Der \"db\"-Container verwendet das Image \"my-db-image\" und hat eine Umgebungsvariable \"MYSQL_ROOT_PASSWORD\" mit dem Wert \"my-password\". Der \"web\"-Container h\u00e4ngt vom \"db\"-Container ab, was bedeutet, dass der \"db\"-Container gestartet wird, bevor der \"web\"-Container gestartet wird.\n\nUm die Container mit Docker Compose zu starten, verwenden Sie den folgenden Befehl:\n\n```\ndocker-compose up\n```\n\nZusammenfassend l\u00e4sst sich sagen, dass es mehrere M\u00f6glichkeiten gibt, Docker-Container zu verbinden. Die gebr\u00e4uchlichste Methode ist die Verwendung von Docker-Netzwerken. Docker-Netzwerke erm\u00f6glichen es Containern, miteinander zu kommunizieren und Ressourcen zu teilen. Sie k\u00f6nnen auch benutzerdefinierte Bridge-Netzwerke erstellen, um die Kommunikation zwischen Containern zu steuern. Docker-Links sind veraltet und werden nicht mehr empfohlen. Docker Compose ist ein Tool, das es Entwicklern erm\u00f6glicht, mehrere Container als eine einzige Anwendung zu definieren und auszuf\u00fchren.","isPartOf":{"@id":"https:\/\/dockerpros.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/#primaryimage"},"image":{"@id":"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/#primaryimage"},"thumbnailUrl":"https:\/\/dockerpros.com\/wp-content\/uploads\/2024\/07\/how-do-i-link-docker-containers_190.jpg","datePublished":"2024-07-21T11:50:52+00:00","breadcrumb":{"@id":"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/#primaryimage","url":"https:\/\/dockerpros.com\/wp-content\/uploads\/2024\/07\/how-do-i-link-docker-containers_190.jpg","contentUrl":"https:\/\/dockerpros.com\/wp-content\/uploads\/2024\/07\/how-do-i-link-docker-containers_190.jpg","width":800,"height":600,"caption":"how-do-i-link-docker-containers-2"},{"@type":"BreadcrumbList","@id":"https:\/\/dockerpros.com\/container-creation-and-management\/how-do-i-link-docker-containers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dockerpros.com\/"},{"@type":"ListItem","position":2,"name":"How do I link Docker containers?"}]},{"@type":"WebSite","@id":"https:\/\/dockerpros.com\/#website","url":"https:\/\/dockerpros.com\/","name":"Docker-Profis","description":"DockerPros \u2013 Ihr umfassender Docker-Ressourcen-Hub","publisher":{"@id":"https:\/\/dockerpros.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dockerpros.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/dockerpros.com\/#organization","name":"Docker-Profis","url":"https:\/\/dockerpros.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dockerpros.com\/#\/schema\/logo\/image\/","url":"https:\/\/dockerpros.com\/wp-content\/uploads\/2024\/07\/Dockerpros_logo_blanco.png","contentUrl":"https:\/\/dockerpros.com\/wp-content\/uploads\/2024\/07\/Dockerpros_logo_blanco.png","width":532,"height":114,"caption":"Dockerpros"},"image":{"@id":"https:\/\/dockerpros.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/dockerpros.com\/#\/schema\/person\/a9b4c3d7f7a8e2b072e77d47b382a3a4","name":"dockerpros","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/dockerpros.com\/#\/schema\/person\/image\/","url":"https:\/\/dockerpros.com\/wp-content\/litespeed\/avatar\/d13b9d4f101de1a7535b404e0c59affd.jpg?ver=1783601465","contentUrl":"https:\/\/dockerpros.com\/wp-content\/litespeed\/avatar\/d13b9d4f101de1a7535b404e0c59affd.jpg?ver=1783601465","caption":"dockerpros"},"sameAs":["https:\/\/dockerpros.com\/"],"url":"https:\/\/dockerpros.com\/de\/author\/dockerpros\/"}]}},"_links":{"self":[{"href":"https:\/\/dockerpros.com\/de\/wp-json\/wp\/v2\/posts\/190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dockerpros.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dockerpros.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dockerpros.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dockerpros.com\/de\/wp-json\/wp\/v2\/comments?post=190"}],"version-history":[{"count":0,"href":"https:\/\/dockerpros.com\/de\/wp-json\/wp\/v2\/posts\/190\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dockerpros.com\/de\/wp-json\/wp\/v2\/media\/356"}],"wp:attachment":[{"href":"https:\/\/dockerpros.com\/de\/wp-json\/wp\/v2\/media?parent=190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dockerpros.com\/de\/wp-json\/wp\/v2\/categories?post=190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dockerpros.com\/de\/wp-json\/wp\/v2\/tags?post=190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}